{"id":120310,"date":"2023-07-01T03:50:36","date_gmt":"2023-07-01T03:50:36","guid":{"rendered":"http:\/\/www.brandon.ddtest.info\/multisite-test\/supreme-court-rules-against-bidens-student-debt-plan-reverse-npr\/"},"modified":"2023-07-01T03:50:36","modified_gmt":"2023-07-01T03:50:36","slug":"supreme-court-rules-against-bidens-student-debt-plan-reverse-npr","status":"publish","type":"post","link":"http:\/\/www.brandon.ddtest.info\/multisite-test\/supreme-court-rules-against-bidens-student-debt-plan-reverse-npr\/","title":{"rendered":"Supreme Court rules against Biden&#039;s student debt plan; Reverse &#8230; &#8211; NPR"},"content":{"rendered":"<p> \n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMidWh0dHBzOi8vd3d3Lm5wci5vcmcvMjAyMy8wNi8zMC8xMTg1NDY3NTM1L3N1cHJlbWUtY291cnQtcnVsZXMtYWdhaW5zdC1iaWRlbnMtc3R1ZGVudC1kZWJ0LXBsYW4tcmV2ZXJzZS1jb3Vyc2Utd3JhcC11cNIBAA?oc=5\" target=\"_blank\" rel=\"noopener\">Supreme Court rules against Biden&#8217;s student debt plan; Reverse &#8230;<\/a>&nbsp;&nbsp;<font color=\"#6f6f6f\">NPR<\/font><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMidWh0dHBzOi8vd3d3Lm5wci5vcmcvMjAyMy8wNi8zMC8xMTg1NDY3NTM1L3N1cHJlbWUtY291cnQtcnVsZXMtYWdhaW5zdC1iaWRlbnMtc3R1ZGVudC1kZWJ0LXBsYW4tcmV2ZXJzZS1jb3Vyc2Utd3JhcC11cNIBAA?oc=5\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Supreme Court rules against Biden&#8217;s student debt plan; Reverse &#8230;&nbsp;&nbsp;NPR Source link<\/p>\n","protected":false},"author":1,"featured_media":120311,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[161],"tags":[],"_links":{"self":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/120310"}],"collection":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/comments?post=120310"}],"version-history":[{"count":0,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/120310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media\/120311"}],"wp:attachment":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media?parent=120310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/categories?post=120310"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/tags?post=120310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}