{"id":52102,"date":"2023-02-05T23:36:13","date_gmt":"2023-02-05T23:36:13","guid":{"rendered":"http:\/\/www.brandon.ddtest.info\/multisite-test\/mpox-public-health-emergency-winds-down-fiercehealthcare\/"},"modified":"2023-02-05T23:36:13","modified_gmt":"2023-02-05T23:36:13","slug":"mpox-public-health-emergency-winds-down-fiercehealthcare","status":"publish","type":"post","link":"http:\/\/www.brandon.ddtest.info\/multisite-test\/mpox-public-health-emergency-winds-down-fiercehealthcare\/","title":{"rendered":"Mpox public health emergency winds down &#8211; FierceHealthcare"},"content":{"rendered":"<p> \n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMihAFodHRwczovL3d3dy5maWVyY2VoZWFsdGhjYXJlLmNvbS9wcm92aWRlcnMvbXBveC1wdWJsaWMtaGVhbHRoLWVtZXJnZW5jeS1vdmVyLWluZmVjdGlvdXMtZGlzZWFzZS1ncm91cHMtc2F5LXRoZXJlcy1zdGlsbC1wbGVudHktbGVhcm7SAQA?oc=5\" target=\"_blank\" rel=\"noopener\">Mpox public health emergency winds down<\/a>&nbsp;&nbsp;<font color=\"#6f6f6f\">FierceHealthcare<\/font><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMihAFodHRwczovL3d3dy5maWVyY2VoZWFsdGhjYXJlLmNvbS9wcm92aWRlcnMvbXBveC1wdWJsaWMtaGVhbHRoLWVtZXJnZW5jeS1vdmVyLWluZmVjdGlvdXMtZGlzZWFzZS1ncm91cHMtc2F5LXRoZXJlcy1zdGlsbC1wbGVudHktbGVhcm7SAQA?oc=5\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mpox public health emergency winds down&nbsp;&nbsp;FierceHealthcare Source link<\/p>\n","protected":false},"author":1,"featured_media":52103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[161],"tags":[],"_links":{"self":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/52102"}],"collection":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/comments?post=52102"}],"version-history":[{"count":0,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/52102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media\/52103"}],"wp:attachment":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media?parent=52102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/categories?post=52102"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/tags?post=52102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}