{"id":61608,"date":"2023-02-26T11:21:36","date_gmt":"2023-02-26T11:21:36","guid":{"rendered":"http:\/\/www.brandon.ddtest.info\/multisite-test\/joe-biden-seeks-to-rescue-student-debt-relief-plan-at-supreme-court-usa-today\/"},"modified":"2023-02-26T11:21:36","modified_gmt":"2023-02-26T11:21:36","slug":"joe-biden-seeks-to-rescue-student-debt-relief-plan-at-supreme-court-usa-today","status":"publish","type":"post","link":"http:\/\/www.brandon.ddtest.info\/multisite-test\/joe-biden-seeks-to-rescue-student-debt-relief-plan-at-supreme-court-usa-today\/","title":{"rendered":"Joe Biden seeks to rescue student debt relief plan at Supreme Court &#8211; USA TODAY"},"content":{"rendered":"<p> \n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMibGh0dHBzOi8vd3d3LnVzYXRvZGF5LmNvbS9zdG9yeS9uZXdzL3BvbGl0aWNzLzIwMjMvMDIvMjYvYmlkZW4tc3R1ZGVudC1kZWJ0LXJlbGllZi1zdXByZW1lLWNvdXJ0LzExMzI2NTQ0MDAyL9IBAA?oc=5\" target=\"_blank\" rel=\"noopener\">Joe Biden seeks to rescue student debt relief plan at Supreme Court<\/a>&nbsp;&nbsp;<font color=\"#6f6f6f\">USA TODAY<\/font><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMibGh0dHBzOi8vd3d3LnVzYXRvZGF5LmNvbS9zdG9yeS9uZXdzL3BvbGl0aWNzLzIwMjMvMDIvMjYvYmlkZW4tc3R1ZGVudC1kZWJ0LXJlbGllZi1zdXByZW1lLWNvdXJ0LzExMzI2NTQ0MDAyL9IBAA?oc=5\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Joe Biden seeks to rescue student debt relief plan at Supreme Court&nbsp;&nbsp;USA TODAY Source link<\/p>\n","protected":false},"author":1,"featured_media":61609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[161],"tags":[],"_links":{"self":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/61608"}],"collection":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/comments?post=61608"}],"version-history":[{"count":0,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/61608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media\/61609"}],"wp:attachment":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media?parent=61608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/categories?post=61608"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/tags?post=61608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}