{"id":61710,"date":"2023-02-26T20:17:39","date_gmt":"2023-02-26T20:17:39","guid":{"rendered":"http:\/\/www.brandon.ddtest.info\/multisite-test\/avoid-these-7-mistakes-when-applying-for-scholarships-paying-for-college-u-s-news-u-s-news-world-report\/"},"modified":"2023-02-26T20:17:39","modified_gmt":"2023-02-26T20:17:39","slug":"avoid-these-7-mistakes-when-applying-for-scholarships-paying-for-college-u-s-news-u-s-news-world-report","status":"publish","type":"post","link":"http:\/\/www.brandon.ddtest.info\/multisite-test\/avoid-these-7-mistakes-when-applying-for-scholarships-paying-for-college-u-s-news-u-s-news-world-report\/","title":{"rendered":"Avoid These 7 Mistakes When Applying for Scholarships | Paying for College | U.S. News &#8211; U.S. News &amp; World Report"},"content":{"rendered":"<p> \n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMifmh0dHBzOi8vd3d3LnVzbmV3cy5jb20vZWR1Y2F0aW9uL2Jlc3QtY29sbGVnZXMvcGF5aW5nLWZvci1jb2xsZWdlL2FydGljbGVzL2F2b2lkLXRoZXNlLW1pc3Rha2VzLXdoZW4tYXBwbHlpbmctZm9yLXNjaG9sYXJzaGlwc9IBAA?oc=5\" target=\"_blank\" rel=\"noopener\">Avoid These 7 Mistakes When Applying for Scholarships | Paying for College | U.S. News<\/a>&nbsp;&nbsp;<font color=\"#6f6f6f\">U.S. News &amp; World Report<\/font><br \/>\n<br \/>\n<br \/><a href=\"https:\/\/news.google.com\/rss\/articles\/CBMifmh0dHBzOi8vd3d3LnVzbmV3cy5jb20vZWR1Y2F0aW9uL2Jlc3QtY29sbGVnZXMvcGF5aW5nLWZvci1jb2xsZWdlL2FydGljbGVzL2F2b2lkLXRoZXNlLW1pc3Rha2VzLXdoZW4tYXBwbHlpbmctZm9yLXNjaG9sYXJzaGlwc9IBAA?oc=5\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avoid These 7 Mistakes When Applying for Scholarships | Paying for College | U.S. News&nbsp;&nbsp;U.S. News &amp; World Report Source link<\/p>\n","protected":false},"author":1,"featured_media":61711,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[161],"tags":[],"_links":{"self":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/61710"}],"collection":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/comments?post=61710"}],"version-history":[{"count":0,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/posts\/61710\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media\/61711"}],"wp:attachment":[{"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/media?parent=61710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/categories?post=61710"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.brandon.ddtest.info\/multisite-test\/wp-json\/wp\/v2\/tags?post=61710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}